{"id":54,"count":1,"description":"","link":"https:\/\/jenesports.com\/en\/tag\/tennis-en\/","name":"Tennis","slug":"tennis-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tennis Archieven - J&amp;Esports<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jenesports.com\/en\/tag\/tennis-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tennis Archieven - J&amp;Esports\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jenesports.com\/en\/tag\/tennis-en\/\" \/>\n<meta property=\"og:site_name\" content=\"J&amp;Esports\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jenesports.com\\\/en\\\/tag\\\/tennis-en\\\/\",\"url\":\"https:\\\/\\\/jenesports.com\\\/en\\\/tag\\\/tennis-en\\\/\",\"name\":\"Tennis Archieven - J&amp;Esports\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jenesports.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jenesports.com\\\/en\\\/tag\\\/tennis-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jenesports.com\\\/en\\\/tag\\\/tennis-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jenesports.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tennis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jenesports.com\\\/#website\",\"url\":\"https:\\\/\\\/jenesports.com\\\/\",\"name\":\"J&amp;Esports\",\"description\":\"Kunstgras\",\"publisher\":{\"@id\":\"https:\\\/\\\/jenesports.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jenesports.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jenesports.com\\\/#organization\",\"name\":\"J&amp;Esports\",\"url\":\"https:\\\/\\\/jenesports.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jenesports.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jenesports.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/jenesports.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo.png\",\"width\":527,\"height\":100,\"caption\":\"J&amp;Esports\"},\"image\":{\"@id\":\"https:\\\/\\\/jenesports.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tennis Archieven - J&amp;Esports","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jenesports.com\/en\/tag\/tennis-en\/","og_locale":"en_US","og_type":"article","og_title":"Tennis Archieven - J&amp;Esports","og_url":"https:\/\/jenesports.com\/en\/tag\/tennis-en\/","og_site_name":"J&amp;Esports","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jenesports.com\/en\/tag\/tennis-en\/","url":"https:\/\/jenesports.com\/en\/tag\/tennis-en\/","name":"Tennis Archieven - J&amp;Esports","isPartOf":{"@id":"https:\/\/jenesports.com\/#website"},"breadcrumb":{"@id":"https:\/\/jenesports.com\/en\/tag\/tennis-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/jenesports.com\/en\/tag\/tennis-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jenesports.com\/en\/"},{"@type":"ListItem","position":2,"name":"Tennis"}]},{"@type":"WebSite","@id":"https:\/\/jenesports.com\/#website","url":"https:\/\/jenesports.com\/","name":"J&amp;Esports","description":"Kunstgras","publisher":{"@id":"https:\/\/jenesports.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jenesports.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jenesports.com\/#organization","name":"J&amp;Esports","url":"https:\/\/jenesports.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jenesports.com\/#\/schema\/logo\/image\/","url":"https:\/\/jenesports.com\/wp-content\/uploads\/2019\/11\/logo.png","contentUrl":"https:\/\/jenesports.com\/wp-content\/uploads\/2019\/11\/logo.png","width":527,"height":100,"caption":"J&amp;Esports"},"image":{"@id":"https:\/\/jenesports.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jenesports.com\/en\/wp-json\/wp\/v2\/tags\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jenesports.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jenesports.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jenesports.com\/en\/wp-json\/wp\/v2\/posts?tags=54"},{"href":"https:\/\/jenesports.com\/en\/wp-json\/wp\/v2\/projecten?tags=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}